{"id":4080,"date":"2021-11-02T15:05:12","date_gmt":"2021-11-02T14:05:12","guid":{"rendered":"http:\/\/baugeschichte.tuwien.ac.at\/website\/?p=4080"},"modified":"2021-12-14T09:16:17","modified_gmt":"2021-12-14T08:16:17","slug":"das-wiener-studentenheim-2","status":"publish","type":"post","link":"http:\/\/baugeschichte.tuwien.ac.at\/website\/das-wiener-studentenheim-2\/","title":{"rendered":"Das Wiener Studentenheim"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Buchpr\u00e4sentation im AzW<\/h2>\n\n\n\n<p>Ein ganzes Jahrhundert Erfahrung und Abenteuer im Bau von Studentenheimen ist Anlass, die daraus gewonnenen Kenntnisse \u2013 in Kooperation mit dem Architektur- und Generalplanungsunternehmen WGA ZT GmbH und dem Forschungsbereich Baugeschichte und Bauforschung der TU Wien \u2013 in einer Publikation zu sammeln.  <\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Wien ist mit rund 200.000 Studierenden eine der gr\u00f6\u00dften Universit\u00e4tsst\u00e4dte im deutschsprachigen Raum. Die Anf\u00e4nge studentischen Wohnens in Wien gehen mit der Gr\u00fcndung der Universit\u00e4t Wien bis ins Jahr 1365 zur\u00fcck. F\u00fcr gerade einmal ca. 10% der Studierenden ist derzeit ein Platz in Studentenheimen vorhanden. Aus diesem Grund entstanden in den letzten Jahren bzw. entstehen in Wien immer mehr Angebote im studentischen (tempor\u00e4ren) Wohnen. Auch haben sich die Anforderungen der Bewohnerinnen und Bewohner an einen Heimplatz \u00fcber die Jahre ver\u00e4ndert. Dieser ist f\u00fcr die meisten von ihnen f\u00fcr einige Jahre ihr unmittelbarer Lebensbereich. Das soziale Umfeld, die Lage im st\u00e4dtischen Raum, die N\u00e4he zu Bildungseinrichtungen, die Qualit\u00e4t der Unterbringung und nat\u00fcrlich die daraus resultierenden Kosten sind zentrale Fragen, die sich Studierende und auch deren Eltern stellen. Eine Antwort auf diese Fragen ist das entwickelte \u201eRaummodul\u201c f\u00fcr \u201eDas Wiener Studentenheim\u201c, welches sich auf Grund von Umfragen unter den Studierenden ergeben hat. Nat\u00fcrlich ist das Bauen und Betreiben von Studentenwohnheimen auch mit Kosten verbunden. Wie k\u00f6nnen sich daher die Gesamtkosten eines Projektes zusammensetzen, welche Themen sind im Betrieb zu beachten und sind die Bewohnerinnen und Bewohner dieser Einrichtungen mit der gebotenen Qualit\u00e4t zufrieden? <\/p>\n\n\n\n<p>Eine Arbeitsgruppe, bestehend aus Vertreterinnen und Vertretern der Akademikerhilfe, der WGA ZT GmbH und der TU Wien \/ Forschungsbereich Baugeschichte und Bauforschung, hat sich dieser Thematik angenommen, das gegenst\u00e4ndliche Werk erarbeitet und herausgegeben. Es richtet sich sowohl an eine Fach- als auch allgemein kultur- und wissenschaftsinteressierte Leserschaft. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Herausgeber: Akademikerhilfe Studentenunterst\u00fctzungsverein <\/p>\n\n\n\n<p>Ein Interview mit den Autorinnen find die au\u00dferdem hier: <br><a href=\"https:\/\/www.architekturzeitung.com\/architekturmagazin\/90-fachliteratur\/4321-untersuchung-des-studentischen-wohnens-in-wien\">Interview Architekturzeitung &#8211; Eine Untersuchung des studentischen Wohnens in Wien.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buchpr\u00e4sentation im AzW Ein ganzes Jahrhundert Erfahrung und Abenteuer im Bau von Studentenheimen ist Anlass, die daraus gewonnenen Kenntnisse \u2013 in Kooperation mit dem Architektur- und Generalplanungsunternehmen WGA ZT GmbH und dem Forschungsbereich Baugeschichte und Bauforschung der TU Wien \u2013 in einer Publikation zu sammeln. Wien ist mit rund 200.000 Studierenden eine der gr\u00f6\u00dften Universit\u00e4tsst\u00e4dte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[66],"class_list":["post-4080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publikationen","tag-osterreich"],"acf":[],"rttpg_featured_image_url":{"full":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"landscape":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"portraits":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"thumbnail":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-150x150.jpg",150,150,true],"medium":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-200x300.jpg",200,300,true],"large":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-683x1024.jpg",683,1024,true],"gs-tiny":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",50,75,false],"xl":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"xxl":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"xxxl":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"xxxxl":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"xxxxxl":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim.jpg",1500,2250,false],"1536x1536":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-1024x1536.jpg",1024,1536,true],"2048x2048":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-1365x2048.jpg",1365,2048,true],"tp-image-grid":["http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-content\/uploads\/2021\/11\/Das-Wiener-Studentenheim-700x700.jpg",700,700,true]},"rttpg_author":{"display_name":"admin","author_link":"http:\/\/baugeschichte.tuwien.ac.at\/website\/author\/admin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"http:\/\/baugeschichte.tuwien.ac.at\/website\/category\/publikationen\/\" rel=\"category tag\">Publikationen<\/a>","rttpg_excerpt":"Buchpr\u00e4sentation im AzW Ein ganzes Jahrhundert Erfahrung und Abenteuer im Bau von Studentenheimen ist Anlass, die daraus gewonnenen Kenntnisse \u2013 in Kooperation mit dem Architektur- und Generalplanungsunternehmen WGA ZT GmbH und dem Forschungsbereich Baugeschichte und Bauforschung der TU Wien \u2013 in einer Publikation zu sammeln. Wien ist mit rund 200.000 Studierenden eine der gr\u00f6\u00dften Universit\u00e4tsst\u00e4dte&hellip;","_links":{"self":[{"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/posts\/4080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/comments?post=4080"}],"version-history":[{"count":0,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/posts\/4080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/media\/4072"}],"wp:attachment":[{"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/media?parent=4080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/categories?post=4080"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/baugeschichte.tuwien.ac.at\/website\/wp-json\/wp\/v2\/tags?post=4080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}